{"id":3120,"date":"2016-05-13T05:18:25","date_gmt":"2016-05-13T05:18:25","guid":{"rendered":"http:\/\/polymathandquixotic.com\/main\/?p=3120"},"modified":"2016-05-14T18:19:31","modified_gmt":"2016-05-14T18:19:31","slug":"guia-para-viajar-a-islandia-barato","status":"publish","type":"post","link":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/","title":{"rendered":"Gu\u00eda para viajar a Islandia barato."},"content":{"rendered":"<p>Viajar siempre es un tema del cual se piensa que es muy caro y que es inalcanzable ir a pa\u00edses que parecieran tan lejanos a nosotros. Si uno cotiza en agencias de viajes online o f\u00edsicas, siempre salen cantidades exageradas las cuales nos hacen desanimarnos m\u00e1s. \u00a0 \u00a0Sin embargo creo que todo es cuesti\u00f3n de saber administrar un poco el dinero y buscar hasta el cansancio las mejores tarifas, temporadas, opciones, etc. \u00a0 Con la ayuda del internet es incre\u00edble lo mucho que nos podemos ahorrar en un viaje. Todo lo que buscamos est\u00e1 a nuestro alcance a trav\u00e9s de la computadora y realizar ese viaje que tanto deseamos puede ser mucho m\u00e1s sencillo y econ\u00f3mico de lo que nos podemos imaginar.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3129\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3129 size-large\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-8-1024x768.jpg\" alt=\"Iceland-8\" width=\"1021\" height=\"766\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-8-1024x768.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-8-300x225.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-8-768x576.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-8-437x328.jpg 437w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-8-875x656.jpg 875w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-8-120x90.jpg 120w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-8.jpg 1600w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><p class=\"wp-caption-text\">Iglesia cerca de Thingvellir<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3133\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3133 size-large\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-12-1024x768.jpg\" alt=\"Iceland-12\" width=\"1021\" height=\"766\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-12-1024x768.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-12-300x225.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-12-768x576.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-12-437x328.jpg 437w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-12-875x656.jpg 875w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-12-120x90.jpg 120w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-12.jpg 1600w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><p class=\"wp-caption-text\">Akureyri, al norte de Islandia.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Hace 3 a\u00f1os viaj\u00e9 por primera vez a Islandia y fue el primer viaje largo que hice sin compa\u00f1\u00eda de alg\u00fan familiar. \u00a0 Algunas personas me han preguntado \u00bfPor qu\u00e9 Islandia? \u00bfC\u00f3mo le hiciste para ir all\u00e1 si es tan caro?\u00a0Por ello decido escribir este post y contar algunos tips u opciones que considero me fueron de gran ayuda. \u00a0 \u00a0Si me hubieran preguntado hace 5 a\u00f1os qu\u00e9 pensaba acerca de los viajes, lo m\u00e1s seguro es que s\u00ed hubiera contestado que era algo muy caro e inalcanzable y que s\u00f3lo pod\u00eda viajar a Estados Unidos por tener familiares que viven ah\u00ed y eso me ahorra hospedaje y otras cosas. \u00a0\u00a0Ver la cantidad de amigos y conocidos que viajaban a todos lados, \u00a0s\u00f3lo me hac\u00eda creer que sus familias ten\u00edan mucho dinero y que eran muy afortunados. Pero esa perspectiva cambi\u00f3 gracias a un amigo de Brasil que, de no salir de su rancho en Brasilia, de pronto consigui\u00f3 trabajo de aeromozo y en un abrir y cerrar de ojos ya hab\u00eda recorrido el mundo y estaba en Islandia de vacaciones. \u00a0Al mismo tiempo descubro en <a href=\"https:\/\/www.youtube.com\/user\/alanxelmundo\" target=\"_blank\">Youtube<\/a> a Alan Estrada, en aquel entonces un conductor del programa &#8220;hoy&#8221;, que empieza a subir videos de su viaje a Islandia. \u00a0Es entonces cuando me pregunt\u00e9 seriamente&#8230; Si ellos pueden ir a donde tanto he querido conocer, \u00bfPor qu\u00e9 no lo puedo hacer?.<\/p>\n<p>Mi gusto por Islandia comenz\u00f3 por ah\u00ed del 2008 mientras escuchaba la m\u00fasica de Sigur R\u00f3s y estando bastante fastidiado de la monoton\u00eda y el caos de la ciudad, buscaba im\u00e1genes de alg\u00fan lugar que me transmitiera tranquilidad, que me conectara con la naturaleza y con el ser humano que somos. \u00a0 Uno entra en autom\u00e1tico y empieza a vivir todos los d\u00edas con prisa sin disfrutar lo que realmente vivimos y el quererme escapar de esa realidad era una necesidad. \u00a0 Antes de investigar sobre Islandia, mi obsesi\u00f3n era con Brasil. Estudi\u00e9 Portugu\u00e9s, conoc\u00ed muchos profesores y amigos brasile\u00f1os y la m\u00fasica de all\u00e1 de los 60s y 70s me causaba\u00a0una nostalgia muy fuerte. \u00a0Sin embargo, el calor jam\u00e1s ha sido mi fuerte por lo que las ganas de querer conocer Brasil se quitaron muy f\u00e1cil considerando que all\u00e1 la temperatura es mucho m\u00e1s elevada que en M\u00e9xico. \u00a0Por ello creo que me fui al otro extremo y buscaba algo m\u00e1s cerca del \u00e1rtico, del fr\u00edo y los glaciares. \u00a0Ah\u00ed fue donde encontr\u00e9 mi verdadera inspiraci\u00f3n y motor.<\/p>\n<p>&nbsp;<\/p>\n<h1>EL VUELO<\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3122\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3122 size-large\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-1-1024x683.jpg\" alt=\"Iceland-1\" width=\"1021\" height=\"681\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-1-1024x683.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-1-300x200.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-1-768x512.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-1-492x328.jpg 492w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-1-984x656.jpg 984w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-1.jpg 1800w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><p class=\"wp-caption-text\">Aeropuerto en Amsterdam. En vuelo de Icelandair<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El primer paso fue ir a agencias como <em>Expedia<\/em>, la cual me daba una cotizaci\u00f3n como de 6,000USD para un boleto de avi\u00f3n\u00a0a Islandia, y ni siquiera en una fecha cercana, sino todo lo contrario. \u00a0 Desde ah\u00ed desech\u00e9 la opci\u00f3n de buscar agencias y prefer\u00ed hacerlo a la inversa. \u00a0 Investigu\u00e9 qu\u00e9 aerol\u00edneas viajaban a Islandia y de qu\u00e9 ciudades llegaban. \u00a0 \u00a0Las opciones no fueron muchas y todo se redujo a <a href=\"http:\/\/www.icelandair.com\" target=\"_blank\"><strong>Icelandair<\/strong><\/a>, la cual es una aerol\u00ednea Islandesa que viaja desde algunas ciudades de Europa e incluso de Estados Unidos. \u00a0(<em>Actualmente ya existe una nueva aerol\u00ednea (tambi\u00e9n islandesa) de bajo costo llamada <a href=\"http:\/\/wowair.com\/\" target=\"_blank\">WOW Airlines<\/a> y que de igual forma vuela desde Estados Unidos, Canad\u00e1 y Europa, lo cual lo hace mucho m\u00e1s conveniente).\u00a0<\/em>En aquel entonces (2013), planeaba mi viaje con una amiga que no ten\u00eda visa para entrar a Estados Unidos por lo que nuestra \u00fanica opci\u00f3n era Europa, ya que s\u00f3lo requer\u00edamos pasaporte como Mexicanos. \u00a0 \u00a0 As\u00ed, al probar diferentes opciones de llegada en el sitio de Icelandair, me di cuenta que lo\u00a0m\u00e1s econ\u00f3mico era viajando desde Oslo (Noruega) o Copenhagen (Dinamarca) (probablemente porque Islandia perteneci\u00f3 a ambos pa\u00edses en su determinado momento). \u00a0Adem\u00e1s hay que tomar en cuenta la temporada, ya que <span style=\"color: #808000;\"><strong>en temporada baja los vuelos y el hospedaje bajan hasta un 50%<\/strong><\/span>. \u00a0 \u00a0Tomando eso en cuenta, decidimos ir en el mes de Febrero. \u00a0 \u00a0<span style=\"color: #808000;\"><strong>La temporada baja en Islandia suele ser de Septiembre a \u00a0principios de Noviembre, y de finales de Enero a Marzo<\/strong><\/span>, lo cual curiosamente coincide con la \u00e9poca de Auroras Boreales en invierno, aunque tambi\u00e9n hay que considerar que el fr\u00edo es mucho m\u00e1s intenso por obvias razones.<\/p>\n<p>Tomando en cuenta lo anterior, decidimos que llegar\u00edamos a Oslo pero ahora ten\u00edamos que ver c\u00f3mo llegar a all\u00e1 desde M\u00e9xico.\u00a0\u00a0Revis\u00e9 algunas opciones con varias aerol\u00edneas y lo m\u00e1s conveniente era a trav\u00e9s de <span style=\"color: #808000;\"><strong>KLM<\/strong><span style=\"color: #000000;\">, s<\/span><\/span>in embargo el precio a\u00fan era un poco alto. \u00a0Convenientemente, en Septiembre sol\u00edan hacer una <span style=\"color: #808000;\"><strong>feria de turismo (<a style=\"color: #808000;\" href=\"http:\/\/www.fitamx.com\/\" target=\"_blank\">FITA<\/a>)<\/strong><\/span> que se llevaba a cabo en la Expo Bancomer de Santa Fe. Por alg\u00fan motivo, dicha feria no se llev\u00f3 acabo en 2015, pero usualmente son en Septiembre cada a\u00f1o y sino, igual hay otras ferias que se hacen durante todo el a\u00f1o como el <a href=\"http:\/\/www.viajayvuela.com.mx\/\" target=\"_blank\">Outlet Viaja y Vuela<\/a>\u00a0o la <a href=\"http:\/\/www.expodestinos.mx\/\" target=\"_blank\">Expo Destino<\/a>s que son en WTC. \u00a0Aunque normalmente siempre encontrar\u00e1s ofertas de meses sin intereses de las agencias, hay que buscar directamente con las aerol\u00edneas. \u00a0En nuestro caso, fuimos a un m\u00f3dulo que ten\u00eda KLM en la FITA y nos aplicaron un 15% o 20% de descuento en el vuelo, lo cual nos ayud\u00f3 mucho para llegar a all\u00e1. \u00a0 Ese era realmente el costo m\u00e1s grande (el vuelo hacia Europa). El vuelo de Noruega a Islandia fue como 3,500 mxn pesos. \u00a0 (Que tambi\u00e9n el\u00a0peso mexicano no estaba tan devaluado como ahora). \u00a0De ese modo, viajamos de la Ciudad de M\u00e9xico a Oslo por KLM con escala de 5 horas en Amsterdam, y de Oslo a Keflavik directo por Icelandair.<\/p>\n<p>Otra opci\u00f3n que llegu\u00e9 a hacer el a\u00f1o pasado es ir a Islandia desde Estados Unidos, lo cual resulta m\u00e1s econ\u00f3mico si uno no encuentra alguna oferta conveniente. \u00a0Usualmente la tarifa m\u00e1s econ\u00f3mica en Icelandair es desde Nueva York o Boston. \u00a0O tambi\u00e9n puedes consultar con WOW Airlines y viajar desde Washington DC o Boston.<\/p>\n<p>La ciudad principal en Islandia es Reikiavik, pero los vuelos internacionales llegan a Keflavik por lo que hay que contratar un servicio de transporte que te lleva a Reikiavik en 1 hora aprox. \u00a0Puedes contratar la opci\u00f3n para que te deje en la central de autobuses (BSI) o que te dejen directamente en tu hotel por una tarifa extra. \u00a0En lo personal he utilizado dos opciones, una es \u00a0<a href=\"http:\/\/grayline.is\/airport-transfer\/\" target=\"_blank\">GrayLine<\/a>, y la otra es con Flybus de\u00a0<a href=\"https:\/\/www.re.is\/flybus\/\" target=\"_blank\">Reykjavik Excursions<\/a>. \u00a0Ambas opciones te dan Wi-Fi en el cami\u00f3n lo cual hace m\u00e1s placentero el traslado. \u00a0Puedes comprar tus tickets para el traslado v\u00eda online, o desde en el mismo vuelo de Icelandair con la aeromoza, o bien en el aeropuerto a tu llegada.<\/p>\n<p>&nbsp;<\/p>\n<h1>HOSPEDAJE<\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3125 aligncenter\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-4-1024x768.jpg\" alt=\"Iceland-4\" width=\"1021\" height=\"766\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-4-1024x768.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-4-300x225.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-4-768x576.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-4-437x328.jpg 437w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-4-875x656.jpg 875w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-4-120x90.jpg 120w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-4.jpg 1600w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Actualmente hay muchas\u00a0formas de conseguir hospedaje econ\u00f3mico, ya que los hoteles pueden llegar a ser mucho m\u00e1s costosos, mi preferida hasta ahora son los hostales. \u00a0Hay una compa\u00f1\u00eda internacional llamada <strong><a href=\"https:\/\/www.hihostels.com\/\" target=\"_blank\">HI Hostels<\/a><\/strong>\u00a0que opera en todo el mundo, inclusive en M\u00e9xico. \u00a0Existen tres hostales en Reikiavik de HI Hostels, uno es el <strong><a href=\"https:\/\/www.facebook.com\/Reykjavik.City.Hostel\/?fref=ts\" target=\"_blank\">City Hostel<\/a><\/strong> (en el \u00e1rea Este, el m\u00e1s econ\u00f3mico de todos pero retirado del centro), otro que es el <strong><a href=\"https:\/\/www.facebook.com\/LoftHostel\/?ref=ts&amp;fref=ts\" target=\"_blank\">Loft<\/a><\/strong> (en el centro, el m\u00e1s nuevo y con una vista incre\u00edble desde la terraza, aunque con mucha gente y ruido), y <a href=\"https:\/\/www.facebook.com\/reykjavikdowntownhostel\/?ref=br_rs\" target=\"_blank\"><strong>Downtown Hostel<\/strong> <\/a>(un poco m\u00e1s hacia el Oeste pero muy cerca del centro, el que m\u00e1s tranquilidad tiene y menos aglomeraciones). \u00a0 \u00a0En lo personal, a mi me gusta mucho el Downtown Hostel, es muy limpio, tranquilo, seguro y adem\u00e1s, tanto este hostal como el Loft, han ganado reconocimientos por ser \u00a1los mejores hostales del mundo!. En el 2015, el primer lugar fue para Loft Hostel, el segundo para Downtown Hostel y tercero era de otro pa\u00eds.<\/p>\n<p>El costo var\u00eda dependiendo el tipo de habitaci\u00f3n que uno quiera. Puedes quedarte en un cuarto para 10 personas (incluso elegir si quieres cuarto de hombres, mujeres o mixto) y por tanto te saldr\u00e1 mucho m\u00e1s econ\u00f3mico (como 350 mxn pesos la noche), o en habitaciones para 4 personas, o el privado para 2 personas con ba\u00f1o incluido. \u00a0 \u00a0En el caso del Downtown Hostel, hay un ba\u00f1o completo dentro de cada habitaci\u00f3n, as\u00ed que si te quedas en el cuarto de 10 personas, el ba\u00f1o es para todos pero usualmente nadie est\u00e1 en la habitaci\u00f3n por lo que es raro que se empalme el quererlos usar. \u00a0Igual en caso de una emergencia puedes salir al \u00e1rea de la cafeter\u00eda o a la cocina y usar los ba\u00f1os disponibles. \u00a0 En el loft,\u00a0los ba\u00f1os est\u00e1n afuera de las habitaciones por lo que se comparten con m\u00e1s gente, pero igual, es muy raro no encontrar uno desocupado.<\/p>\n<p>Otra opci\u00f3n de hostales es el <strong><a href=\"https:\/\/www.facebook.com\/KexHostel\/?fref=ts\" target=\"_blank\">KEX Hostel<\/a><\/strong> que es muy conocido por hacer conciertos durante festivales como el <a href=\"http:\/\/icelandairwaves.is\/\" target=\"_blank\"><strong>Iceland Airwaves<\/strong><\/a> en Octubre. \u00a0Est\u00e1 ubicado muy cerca del centro, y los costos pueden ser un poco m\u00e1s econ\u00f3micos. Sin embargo al ser m\u00e1s popular, puede haber m\u00e1s gente y mayor ruido. \u00a0El \u00e1rea de regaderas es \u00e1rea com\u00fan como en un campo militar, por lo que si lo que buscas es privacidad a la hora de darte un ba\u00f1o, este tal vez no sea el lugar para ti ( Los ba\u00f1os de hombres y de mujeres est\u00e1n separados por si queda la duda). \u00a0Sin embargo esto es algo muy com\u00fan en Islandia, sobre todo en las albercas las cuales son muy populares.\u00a0Las regaderas es \u00e1rea abierta y las reglas dicen que no puedes ba\u00f1arte con traje de ba\u00f1o por higiene, pero ya hablar\u00e9 de esto en otra ocasi\u00f3n&#8230;<\/p>\n<p>Adem\u00e1s de los hostales, existen nuevos m\u00e9todos de alojamiento como <strong><a href=\"https:\/\/www.airbnb.mx\/\" target=\"_blank\">AirBnb<\/a><\/strong> o <strong><a href=\"https:\/\/www.couchsurfing.com\/\" target=\"_blank\">CouchSurfing<\/a><\/strong>\u00a0. \u00a0Por un lado, AirBnb es un sitio donde puedes hospedarte en casa de alg\u00fan nativo o de alguien que est\u00e9 rentando un espacio en su casa, puede ser desde un cuarto privado o compartido, hasta simplemente un sofa. \u00a0A veces te incluyen desayunos, o comidas, pero eso ya depende del anfitri\u00f3n. \u00a0Puedes revisar las casas cerca del \u00e1rea a donde quieras ir (tal vez del centro) y ver qu\u00e9 opciones hay y sobre todo dejarte guiar un poco por las rese\u00f1as que son muy importantes al tomar una decisi\u00f3n. \u00a0 \u00a0Y por otra parte, CouchSurfing que es b\u00e1sicamente lo mismo pero sin costo alguno. La diferencia con esto es que no tienes como tal la seguridad de que llegar\u00e1s a alg\u00fan lugar c\u00f3modo pero de igual forma te puedes guiar por las rese\u00f1as y si lo tuyo es irte de mochila sin importar en donde dormir, creo esta opci\u00f3n ser\u00e1 la m\u00e1s conveniente.<\/p>\n<p>La parte buena de usar AirBnb o CouchSurfing es conocer y convivir con los locales, conocer sus costumbres, escuchar sus consejos, tips y tal vez hasta te puedan dar un ride o incluirte en alg\u00fan paseo. \u00a0Sin embargo, AirBnb puede ser un poco m\u00e1s costoso que un hostal y ah\u00ed depender\u00e1 del tipo de gente que quieras conocer en tu viaje. Si quieres convivir con otros viajeros de todas partes, lo mejor ser\u00e1 quedarte en un hostal y conocer gente en la cocina, en las habitaciones. \u00a0Pero si quieres conocer m\u00e1s sobre la cultura local, lo mejor es utilizar AirBnb o CouchSurfing, aunque tambi\u00e9n puede que te hospedes con un extranjero que renta un espacio&#8230; es cuesti\u00f3n de buscar lo que m\u00e1s te agrade.<\/p>\n<p>&nbsp;<\/p>\n<h1>COMIDA<\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3126\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3126 size-large\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-1024x1024.jpg\" alt=\"Iceland-5\" width=\"1021\" height=\"1021\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-1024x1024.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-150x150.jpg 150w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-300x300.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-768x768.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-90x90.jpg 90w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-328x328.jpg 328w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-656x656.jpg 656w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5-500x500.jpg 500w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-5.jpg 1200w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><p class=\"wp-caption-text\">B\u00f3nus<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Salir a buscar restaurantes va a ser costoso. Por lo general, Islandia es algo caro, as\u00ed que salir a buscar comida puede llegar a ser un lujo. \u00a0Mi recomendaci\u00f3n en este aspecto\u00a0es aplicar lo que hacen los locales y lo que hacemos nosotros en nuestra casa&#8230; ir al super y cocinar algo. \u00a0La mejor opci\u00f3n es ir a un supermercado llamado &#8220;<strong><a href=\"http:\/\/www.bonus.is\/\" target=\"_blank\">B\u00f3nus<\/a><\/strong>&#8220;, los precios van a ser much\u00edsimo m\u00e1s bajos que en el resto de las tiendas. \u00a0Sobre todo si te vas a lugares cercanos al centro o peque\u00f1as tiendas parecidas al 7 eleven, la comida te va a salir muy cara y terminar\u00e1s pagando el doble o m\u00e1s de lo que realmente cuesta. \u00a0Tambi\u00e9n puedes ir a otro supermercado llamado &#8220;<strong><a href=\"http:\/\/kronan.is\/\" target=\"_blank\">Kr\u00f3nan<\/a><\/strong>&#8221; donde encontrar\u00e1s mayor variedad sobre todo en alimentos org\u00e1nicos y saludables, pero tambi\u00e9n ser\u00e1 un poco m\u00e1s costoso, por lo que yo recomendar\u00eda <a href=\"http:\/\/www.bonus.is\/verslun\/fiskislod\/\" target=\"_blank\">localizar el B\u00f3nus m\u00e1s cercano<\/a> al lugar donde te est\u00e9s alojando y hacer ah\u00ed el super de la semana. \u00a0Encontrar\u00e1s precios muy similares a los que estamos acostumbrados en M\u00e9xico. \u00a0Y si no sabes cocinar, nunca falla comprar un poco de pan y queso para hacerte un sandwich o de plano si quieres ahorrar mucho, latas de at\u00fan.<\/p>\n<p>Otra opci\u00f3n que puede resultar econ\u00f3mica es revisar los paquetes que te ofrecen los hostales. En muchas ocasiones te pueden incluir el desayuno como complemento que normalmente es jugo, fruta y alg\u00fan cereal. \u00a0En mi opini\u00f3n, creo es m\u00e1s econ\u00f3mico y llenador ir al super. Puedes comprarte tu propio cereal, leche e inclusive tratar de probar productos locales (aunque siempre encontrar\u00e1s una sorpresa en los sabores).<\/p>\n<p>Entre las comidas t\u00edpicas de Islandia est\u00e1 el tibur\u00f3n fermentado pero para los extranjeros puede ser un sabor muy extra\u00f1o, por lo que otra comida t\u00edpica para los Islandeses es un puesto de hotdogs llamado &#8220;<strong><a href=\"https:\/\/www.tripadvisor.com.mx\/Restaurant_Review-g189970-d1852122-Reviews-Baejarins_Beztu_Pylsur-Reykjavik_Capital_Region.html\" target=\"_blank\">B\u00e6jarins Beztu Pylsur<\/a><\/strong>&#8220;, el cual es un carrito que opera desde 1937 y vende los m\u00e1s exquisitos hot dogs. \u00a0 Pide &#8220;one with everything&#8221; (uno con todo) y\u00a0sabr\u00e1s a qu\u00e9 me refiero. \u00a0El costo del hotdog (en 2016) es de 350\u201338 ISK. ( 55 pesos mexicanos).<\/p>\n<p>&nbsp;<\/p>\n<h1>ENTRETENIMIENTO Y QU\u00c9 VER<\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3132\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3132 size-large\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-11-1024x768.jpg\" alt=\"Iceland-11\" width=\"1021\" height=\"766\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-11-1024x768.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-11-300x225.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-11-768x576.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-11-437x328.jpg 437w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-11-875x656.jpg 875w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-11-120x90.jpg 120w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-11.jpg 1600w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><p class=\"wp-caption-text\">Perlan (The Pearl)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En Reikiavik hay muchas cosas para ver y que son completamente gratis. \u00a0Puedes empezar por visitar uno de los edificios m\u00e1s emblem\u00e1ticos de la ciudad, el <strong><a href=\"https:\/\/www.google.com.mx\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=11&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwjEkP2VgNbMAhXC44MKHR9tAkkQFghMMAo&amp;url=http%3A%2F%2Fwww.hallgrimskirkja.is%2Fenglish%2F&amp;usg=AFQjCNFCC0fXfRYiJITGDt-_ujpWIvNbNg&amp;sig2=n7j8aMMMEoAuiccOwfLBvA\" target=\"_blank\">Hallgr\u00edmskirkja<\/a><\/strong>, la cual es la iglesia principal y mide 73 metros de altura. \u00a0La entrada es gratuita, es iglesia Luterana, puedes entrar y si tienes suerte, hasta podr\u00e1s ver a alguien tocando el majestuoso \u00f3rgano de 15 metros de altura. Si quieres subir al mirador, el costo es como de 60 pesos mexicanos. \u00a0Es el edificio m\u00e1s alto de Reikiavik, as\u00ed que vale la pena.<\/p>\n<p>Y si de tener buena vista se trata, tambi\u00e9n puedes visitar <strong><a href=\"https:\/\/www.google.com.mx\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=3&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwjH6paPgNbMAhXq7oMKHcsTCXAQFggpMAI&amp;url=http%3A%2F%2Fwww.perlan.is%2F%3Flang%3Den&amp;usg=AFQjCNHWKTA1HSNPmPzT4aVcdm4bEn_8oA&amp;sig2=Qb2_lxheqZSpdRp68yUKig\" target=\"_blank\">Perlan<\/a><\/strong>, que es un edificio futurista con una base de 6 tanques de agua caliente. Dentro, en el 5to piso, est\u00e1 un restaurante giratorio, pero si no quieres ir a comer (porque el precio es bastante elevado), puedes entrar solamente al edificio y en el 4to piso salir al mirador sin ning\u00fan costo. Desde ah\u00ed tendr\u00e1s un paisaje inigualable de la ciudad y del mar.<\/p>\n<p>Otro de los edificios emblem\u00e1ticos que puedes visitar en la ciudad es el <strong><a href=\"https:\/\/www.google.com.mx\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwiJ85qvgNbMAhUIw4MKHU6XAksQFggjMAA&amp;url=http%3A%2F%2Fen.harpa.is%2F&amp;usg=AFQjCNGk52fTRIH2g_kYeZJIQ4l4lO-XJg&amp;sig2=L4lY4EqQhhNXiAIPquSC-w\" target=\"_blank\">Harpa Concert Hall<\/a><\/strong>, el cual es un edificio moderno que fue inaugurado apenas en 2011. Adem\u00e1s de ser una sala de conciertos, puedes entrar a ver las tiendas de artesan\u00edas y dise\u00f1o, as\u00ed como la cafeter\u00eda, y observar la grandiosa vista del mar dentro del edificio.<\/p>\n<p>Como ver\u00e1s, hay muchos escenarios donde puedes detenerte a admirar la belleza Islandesa. A la orilla\u00a0del mar, puedes visitar una de las esculturas m\u00e1s retratadas de Reikiavik, el <span style=\"color: #808000;\"><strong>S\u00f3lfar<\/strong><\/span>, el cu\u00e1l est\u00e1 a unos pasos del Harpa. Representa el &#8220;barco de los sue\u00f1os&#8221;, llenos de esperanzas y nuevos anhelos al descubrir un nuevo territorio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3136\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3136 size-large\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-1024x1024.jpg\" alt=\"Iceland-13\" width=\"1021\" height=\"1021\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-1024x1024.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-150x150.jpg 150w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-300x300.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-768x768.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-90x90.jpg 90w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-328x328.jpg 328w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-656x656.jpg 656w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13-500x500.jpg 500w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-13.jpg 1200w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><p class=\"wp-caption-text\">12 T\u00f3nar<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Otra gran idea, si disfrutas de la m\u00fasica, es visitar las tiendas de discos locales. Puedes ir a tiendas como <a href=\"http:\/\/www.12tonar.is\/\" target=\"_blank\"><strong>12 Tonar<\/strong><\/a>\u00a0y seleccionar variedad de discos y escucharlos en las peque\u00f1as grabadoras que tienen disponibles. Esta es una gran opci\u00f3n para descubrir bandas locales y m\u00fasica tradicional. Preg\u00fantale al vendedor si puedes escuchar los discos que elegiste y \u00e9l te dar\u00e1 unos abiertos para que los escuches con unos aud\u00edfonos en la estancia mientras contemplas la decoraci\u00f3n n\u00f3rdica del lugar. \u00a0 \u00a0Ahora, que si te animas a comprar alg\u00fan disco, tal vez te convenga m\u00e1s visitar <a href=\"https:\/\/www.google.com.mx\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwj27aKvg9bMAhXm5YMKHQ9OAOAQFggcMAA&amp;url=http%3A%2F%2Fluckyrecords.is%2F&amp;usg=AFQjCNGWfzojbPjRYruka3vlusOD6qyVMQ&amp;sig2=6A8hG7FsRa12kgw5OUuL5A\" target=\"_blank\"><strong>Lucky Records<\/strong><\/a> a unas cuadras m\u00e1s hacia el Este, ya que ah\u00ed podr\u00e1s tambi\u00e9n escuchar la m\u00fasica que selecciones pero a un precio m\u00e1s econ\u00f3mico. Adem\u00e1s tienen una variedad de discos de segunda mano que te pueden interesar.<\/p>\n<p>&nbsp;<\/p>\n<h1>TRANSPORTE Y VISITAS FUERA DE REIKIAVIK<\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_3131\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3131 size-large\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-10-1024x768.jpg\" alt=\"Iceland-10\" width=\"1021\" height=\"766\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-10-1024x768.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-10-300x225.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-10-768x576.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-10-437x328.jpg 437w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-10-875x656.jpg 875w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-10-120x90.jpg 120w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-10.jpg 1600w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><p class=\"wp-caption-text\">Playa de Reynishfjara<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Si buscas salirte un poco de la ciudad, \u00a1haces bien!. La belleza de Islandia est\u00e1 en toda la isla, no s\u00f3lo en Reikiavik. \u00a0Uno de mis lugares favoritos es <span style=\"color: #808000;\"><strong>Reynishfjara<\/strong><\/span>, que es una playa de arena negra muy cerca del pueblo<span style=\"color: #808000;\"><strong> V\u00edk<\/strong><\/span>, al sur del pa\u00eds. \u00a0Pero para llegar all\u00e1 necesitar\u00e1s transporte. \u00a0Lo m\u00e1s econ\u00f3mico, definitivamente, es unirte a otros viajeros que conozcas en el camino, y ver si entre todos pueden alquilar un auto y repartirse el gasto de gasolina, de este modo podr\u00e1n pasar m\u00e1s tiempo en los lugares que quieran y a un bajo costo. \u00a0 Incluso puedes ver las opciones de alojamiento de HI Hostels en otros pueblos de Islandia para poder viajar con mayor tranquilidad. \u00a0 \u00a0Ahora que si lo tuyo no es socializar y prefieres rentar un auto por tu cuenta, te puede salir un poco m\u00e1s caro ya que la renta de autos no es tan econ\u00f3mico en Islandia.<\/p>\n<p>Y\u00a0si lo tuyo no es socializar, ni sabes manejar un auto, tambi\u00e9n puedes tomar camiones que te llevar\u00e1n a esos destinos. \u00a0Consulta el sitio de <strong><a href=\"http:\/\/www.straeto.is\/english\/popular-destinations\/\">Straeto<\/a><\/strong>\u00a0y checa las distintas rutas que hacen por toda la isla y los horarios. \u00a0Hay muchas paradas donde puedes subirte. Inclusive como transporte local dentro de Reikiavik tambi\u00e9n lo puedes utilizar y el costo no es muy alto. \u00a0O si prefieres caminar en la ciudad, igual lo puedes hacer, pero despu\u00e9s de un rato te cansar\u00e1s, sobre todo para ver otros edificios y museos que no est\u00e9n en el centro. \u00a0El boleto de ida te costar\u00e1 como 50 mxn pesos. \u00a0Son camiones amarillos y son el \u00fanico sistema de transporte p\u00fablico que hay dentro de la ciudad (sin contar los taxis). \u00a0Toma en cuenta que los conductores al cobrarte, no llevan cambio ni aceptan tarjetas, por lo que deber\u00e1s llevar el costo exacto de tu boleto (350 ISK). \u00a0Tambi\u00e9n puedes comprar tarjetas para usar m\u00e1s tiempo.<\/p>\n<p>Estos son los costos:<\/p>\n<p>24 horas por 700 ISK<br \/>\n72 horas por 1700 ISK<br \/>\n30 d\u00edas por 7000 ISK<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3127 aligncenter\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-6-1024x768.jpg\" alt=\"Iceland-6\" width=\"1021\" height=\"766\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-6-1024x768.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-6-300x225.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-6-768x576.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-6-437x328.jpg 437w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-6-875x656.jpg 875w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-6-120x90.jpg 120w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-6.jpg 1600w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3128 aligncenter\" src=\"http:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-1024x1024.jpg\" alt=\"Iceland-7\" width=\"1021\" height=\"1021\" srcset=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-1024x1024.jpg 1024w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-150x150.jpg 150w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-300x300.jpg 300w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-768x768.jpg 768w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-90x90.jpg 90w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-328x328.jpg 328w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-656x656.jpg 656w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7-500x500.jpg 500w, https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2016\/05\/Iceland-7.jpg 1200w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En general Islandia puede ser un pa\u00eds costoso pero si sabes administrarte podr\u00e1s ahorrar de muchas formas y dejando que tu \u00fanico gasto fuerte sea el avi\u00f3n. Actualmente hay ofertas a trav\u00e9s de WOW Airlines que te llevan de Estados Unidos a Keflavik por muy bajo costo, y en total con el vuelo de M\u00e9xico a Estados Unidos, te puede salir un viaje a Islandia por menos de 10,000 mxn pesos. \u00a0Y ya despu\u00e9s sabr\u00e1s organizar el resto de tu presupuesto para comidas y hospedaje. \u00a0 \u00a0En cuanto a transporte, los Tours suelen ser caros y te dan el tiempo contado para visitar ciertos lugares, por lo que creo es mejor investigar y ver la forma de moverte por tu cuenta ya sea en cami\u00f3n o en auto con amigos.<\/p>\n<p>Islandia es un pa\u00eds fascinante, lleno de naturaleza y creatividad en todos sus aspectos. Si aprovechas la temporada de invierno y quieres ver las <span style=\"color: #808000;\"><strong>Auroras Boreales<\/strong><\/span>, puedes hacerlo con amigos, aunque en esta parte considero que s\u00ed vale la pena contratar un tour que te puede costar alrededor de 500 pesos para que en autob\u00fas te alejen de la ciudad y las luces, y a su vez te mantengan dentro del cami\u00f3n en un ambiente c\u00e1lido. Normalmente cuando hace m\u00e1s fr\u00edo es cuando se pueden ver las Auroras Boreales por lo que las temperaturas suelen ser muy bajas y necesitar\u00e1s un lugar en d\u00f3nde refugiarte. \u00a0Contratar un tour ser\u00e1 una muy buena idea.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viajar siempre es un tema del cual se piensa que es muy caro y que es inalcanzable ir a pa\u00edses que parecieran tan lejanos a nosotros. Si uno cotiza en agencias de viajes online o f\u00edsicas, siempre salen cantidades exageradas las cuales nos hacen desanimarnos m\u00e1s. \u00a0 \u00a0Sin embargo creo &hellip;<\/p>\n<div class=\"wrap-excerpt-more\"><a class=\"excerpt-more\" href=\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/\">Continue reading<\/a><\/div>\n","protected":false},"author":2,"featured_media":2963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[123],"tags":[126,125,121,83,120],"class_list":["post-3120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes","tag-barato","tag-iceland","tag-islandia","tag-mexico","tag-viajes","post-with-media","post-with-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gu\u00eda para viajar a Islandia barato. &#8226; Polymath &amp; Quixotic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda para viajar a Islandia barato. &#8226; Polymath &amp; Quixotic\" \/>\n<meta property=\"og:description\" content=\"Viajar siempre es un tema del cual se piensa que es muy caro y que es inalcanzable ir a pa\u00edses que parecieran tan lejanos a nosotros. Si uno cotiza en agencias de viajes online o f\u00edsicas, siempre salen cantidades exageradas las cuales nos hacen desanimarnos m\u00e1s. \u00a0 \u00a0Sin embargo creo &hellip;Continue reading\" \/>\n<meta property=\"og:url\" content=\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/\" \/>\n<meta property=\"og:site_name\" content=\"Polymath &amp; Quixotic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/polymathandquixotic\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-13T05:18:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-14T18:19:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Polymath&amp;Quixotic\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Polymath&amp;Quixotic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/\"},\"author\":{\"name\":\"Polymath&amp;Quixotic\",\"@id\":\"https:\/\/polymathandquixotic.com\/main\/#\/schema\/person\/01bc30080d37cd6df2d63e2a499ef221\"},\"headline\":\"Gu\u00eda para viajar a Islandia barato.\",\"datePublished\":\"2016-05-13T05:18:25+00:00\",\"dateModified\":\"2016-05-14T18:19:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/\"},\"wordCount\":3660,\"image\":{\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg\",\"keywords\":[\"barato\",\"iceland\",\"Islandia\",\"mexico\",\"viajes\"],\"articleSection\":[\"viajes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/\",\"url\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/\",\"name\":\"Gu\u00eda para viajar a Islandia barato. &#8226; Polymath &amp; Quixotic\",\"isPartOf\":{\"@id\":\"https:\/\/polymathandquixotic.com\/main\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg\",\"datePublished\":\"2016-05-13T05:18:25+00:00\",\"dateModified\":\"2016-05-14T18:19:31+00:00\",\"author\":{\"@id\":\"https:\/\/polymathandquixotic.com\/main\/#\/schema\/person\/01bc30080d37cd6df2d63e2a499ef221\"},\"breadcrumb\":{\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#primaryimage\",\"url\":\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg\",\"contentUrl\":\"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/polymathandquixotic.com\/main\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gu\u00eda para viajar a Islandia barato.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/polymathandquixotic.com\/main\/#website\",\"url\":\"https:\/\/polymathandquixotic.com\/main\/\",\"name\":\"Polymath &amp; Quixotic\",\"description\":\"FOTO \u00b7 VIDEO \u00b7 DISE\u00d1O\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/polymathandquixotic.com\/main\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/polymathandquixotic.com\/main\/#\/schema\/person\/01bc30080d37cd6df2d63e2a499ef221\",\"name\":\"Polymath&amp;Quixotic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/5d00122879f8a55ebb91c67a01ceb7a28a43f3e5e0435b552e4020757446aa15?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5d00122879f8a55ebb91c67a01ceb7a28a43f3e5e0435b552e4020757446aa15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5d00122879f8a55ebb91c67a01ceb7a28a43f3e5e0435b552e4020757446aa15?s=96&d=mm&r=g\",\"caption\":\"Polymath&amp;Quixotic\"},\"url\":\"https:\/\/polymathandquixotic.com\/main\/author\/polymathquixotic\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gu\u00eda para viajar a Islandia barato. &#8226; Polymath &amp; Quixotic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/","og_locale":"es_ES","og_type":"article","og_title":"Gu\u00eda para viajar a Islandia barato. &#8226; Polymath &amp; Quixotic","og_description":"Viajar siempre es un tema del cual se piensa que es muy caro y que es inalcanzable ir a pa\u00edses que parecieran tan lejanos a nosotros. Si uno cotiza en agencias de viajes online o f\u00edsicas, siempre salen cantidades exageradas las cuales nos hacen desanimarnos m\u00e1s. \u00a0 \u00a0Sin embargo creo &hellip;Continue reading","og_url":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/","og_site_name":"Polymath &amp; Quixotic","article_publisher":"https:\/\/www.facebook.com\/polymathandquixotic","article_published_time":"2016-05-13T05:18:25+00:00","article_modified_time":"2016-05-14T18:19:31+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg","type":"image\/jpeg"}],"author":"Polymath&amp;Quixotic","twitter_misc":{"Escrito por":"Polymath&amp;Quixotic","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#article","isPartOf":{"@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/"},"author":{"name":"Polymath&amp;Quixotic","@id":"https:\/\/polymathandquixotic.com\/main\/#\/schema\/person\/01bc30080d37cd6df2d63e2a499ef221"},"headline":"Gu\u00eda para viajar a Islandia barato.","datePublished":"2016-05-13T05:18:25+00:00","dateModified":"2016-05-14T18:19:31+00:00","mainEntityOfPage":{"@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/"},"wordCount":3660,"image":{"@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#primaryimage"},"thumbnailUrl":"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg","keywords":["barato","iceland","Islandia","mexico","viajes"],"articleSection":["viajes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/","url":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/","name":"Gu\u00eda para viajar a Islandia barato. &#8226; Polymath &amp; Quixotic","isPartOf":{"@id":"https:\/\/polymathandquixotic.com\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#primaryimage"},"image":{"@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#primaryimage"},"thumbnailUrl":"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg","datePublished":"2016-05-13T05:18:25+00:00","dateModified":"2016-05-14T18:19:31+00:00","author":{"@id":"https:\/\/polymathandquixotic.com\/main\/#\/schema\/person\/01bc30080d37cd6df2d63e2a499ef221"},"breadcrumb":{"@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#primaryimage","url":"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg","contentUrl":"https:\/\/polymathandquixotic.com\/main\/wp-content\/uploads\/2015\/11\/Iceland-181.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/polymathandquixotic.com\/main\/guia-para-viajar-a-islandia-barato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/polymathandquixotic.com\/main\/"},{"@type":"ListItem","position":2,"name":"Gu\u00eda para viajar a Islandia barato."}]},{"@type":"WebSite","@id":"https:\/\/polymathandquixotic.com\/main\/#website","url":"https:\/\/polymathandquixotic.com\/main\/","name":"Polymath &amp; Quixotic","description":"FOTO \u00b7 VIDEO \u00b7 DISE\u00d1O","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/polymathandquixotic.com\/main\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/polymathandquixotic.com\/main\/#\/schema\/person\/01bc30080d37cd6df2d63e2a499ef221","name":"Polymath&amp;Quixotic","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d00122879f8a55ebb91c67a01ceb7a28a43f3e5e0435b552e4020757446aa15?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d00122879f8a55ebb91c67a01ceb7a28a43f3e5e0435b552e4020757446aa15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d00122879f8a55ebb91c67a01ceb7a28a43f3e5e0435b552e4020757446aa15?s=96&d=mm&r=g","caption":"Polymath&amp;Quixotic"},"url":"https:\/\/polymathandquixotic.com\/main\/author\/polymathquixotic\/"}]}},"_links":{"self":[{"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/posts\/3120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/comments?post=3120"}],"version-history":[{"count":8,"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/posts\/3120\/revisions"}],"predecessor-version":[{"id":3142,"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/posts\/3120\/revisions\/3142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/media\/2963"}],"wp:attachment":[{"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/media?parent=3120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/categories?post=3120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/polymathandquixotic.com\/main\/wp-json\/wp\/v2\/tags?post=3120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}